{"id":8456,"date":"2017-04-26T06:37:19","date_gmt":"2017-04-26T06:37:19","guid":{"rendered":"https:\/\/cerlalc.org\/se-presentaron-los-datos-del-2016-del-observatorio-de-pirateria-y-habitos-de-consumo-digitales-en-espana\/"},"modified":"2017-04-26T06:37:19","modified_gmt":"2017-04-26T06:37:19","slug":"se-presentaron-los-datos-del-2016-del-observatorio-de-pirateria-y-habitos-de-consumo-digitales-en-espana","status":"publish","type":"post","link":"https:\/\/cerlalc.org\/pt-br\/se-presentaron-los-datos-del-2016-del-observatorio-de-pirateria-y-habitos-de-consumo-digitales-en-espana\/","title":{"rendered":"Se presentaron los datos del 2016 del Observatorio de Pirater\u00eda y H\u00e1bitos de Consumo Digitales en Espa\u00f1a"},"content":{"rendered":"<p>El director general de Industrias Culturales y del Libro, \u00d3scar S\u00e1enz de Santa Mar\u00eda, ha participado en la mesa de presentaci\u00f3n de los datos del 2016 del Observatorio de Pirater\u00eda y H\u00e1bitos de Consumo Digitales en Espa\u00f1a, celebrada el pasado martes en la Secretar\u00eda de Estado de Cultura. El estudio de los datos anuales sobre las actitudes y acceso ilegal para las industrias del cine, m\u00fasica, libros, videojuegos y f\u00fatbol ha sido elaborado por la consultora GFK a instancias de La Coalici\u00f3n de creadores e industrias de contenidos y LaLiga.<\/p>\n<p>En el documento presentado se destaca que estamos \u201cante el primer descenso de la pirater\u00eda en los \u00faltimos 10 a\u00f1os y es una gran oportunidad para revertir el gran perjuicio que ocasiona a los creadores, a las industrias pero tambi\u00e9n al empleo, las arcas p\u00fablicas y la competitividad de nuestro pa\u00eds en el mercado global\u201d. A lo largo de 2016, se han contabilizado 4.128 millones de accesos ilegales a contenidos, un 4,2% menos que en 2015, por un valor de 23.294 millones de euros (-3,2%), seg\u00fan el estudio.<\/p>\n<p>A partir del an\u00e1lisis de los datos de 2016, el Observatorio de Pirater\u00eda y H\u00e1bitos de Consumo Digitales afirma que \u201cun escenario sin pirater\u00eda permitir\u00eda crear 21.697 nuevos puestos de trabajo directos y unos 110.000 empleos indirectos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director general de Industrias Culturales y del Libro, \u00d3scar S\u00e1enz de Santa Mar\u00eda, ha participado en la mesa de presentaci\u00f3n de los datos del 2016 del Observatorio de Pirater\u00eda y H\u00e1bitos de Consumo Digitales en Espa\u00f1a, celebrada el pasado martes en la Secretar\u00eda de Estado de Cultura.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":""},"categories":[2464],"tags":[2493,2509],"areas":[],"countries":[],"programas":[],"coauthors":[],"_links":{"self":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts\/8456"}],"collection":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/comments?post=8456"}],"version-history":[{"count":0,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts\/8456\/revisions"}],"wp:attachment":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/media?parent=8456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/categories?post=8456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/tags?post=8456"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/areas?post=8456"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/countries?post=8456"},{"taxonomy":"programas","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/programas?post=8456"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/coauthors?post=8456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}