{"id":8841,"date":"2016-11-05T17:58:12","date_gmt":"2016-11-05T17:58:12","guid":{"rendered":"https:\/\/cerlalc.org\/aspectos-economicos-del-sector-audiovisual-en-iberoamerica\/"},"modified":"2016-11-05T17:58:12","modified_gmt":"2016-11-05T17:58:12","slug":"aspectos-economicos-del-sector-audiovisual-en-iberoamerica","status":"publish","type":"post","link":"https:\/\/cerlalc.org\/pt-br\/aspectos-economicos-del-sector-audiovisual-en-iberoamerica\/","title":{"rendered":"Aspectos econ\u00f3micos del sector audiovisual en Iberoam\u00e9rica"},"content":{"rendered":"<p>Por Diana Marcela Rey<\/p>\n<p>El sector audiovisual,\u00a0compuesto por el cine, el video, la televisi\u00f3n abierta y la televisi\u00f3n por suscripci\u00f3n, es uno de los que m\u00e1s contribuye a las econom\u00edas iberoamericanas entre las Industrias Protegidas por el Derecho de Autor, IPDA, por sus elevados aportes al Producto Interno Bruto, PIB, sus altos niveles de facturaci\u00f3n y el volumen de sus exportaciones.<\/p>\n<p>Para el a\u00f1o 1997 los audiovisuales generaron en Argentina, Brasil, Chile, M\u00e9xico, Venezuela, Colombia, Bolivia, Ecuador, Per\u00fa, Estados Unidos, Espa\u00f1a y Portugal un total de 17.210 millones de d\u00f3lares, de los cuales el 51,5 por ciento proced\u00eda de la televisi\u00f3n abierta publicitaria, un 31 por ciento de la televisi\u00f3n de pago y un 17 por ciento del cine-v\u00eddeo, como lo afirm\u00f3 Enrique Bustamante en su estudio \u201cLa televisi\u00f3n en Iberoam\u00e9rica: el nudo de cooperaci\u00f3n cultural\u201d.<\/p>\n<p>El predominio de la televisi\u00f3n p\u00fablica en relaci\u00f3n a la se\u00f1al por suscripci\u00f3n privada y el cine se mantuvo durante los \u00faltimos a\u00f1os, al punto que seg\u00fan el estudio de Becerra y Mastrini, con a\u00f1o base 2005, los pa\u00edses latinoamericanos recaudaron 12.879 millones de d\u00f3lares en el subsector, de los cuales tan s\u00f3lo 756,83 millones fueron provenientes del cine. Una tendencia que tambi\u00e9n se ve para el caso espa\u00f1ol, donde seg\u00fan datos de la investigaci\u00f3n de DBK Madrid para el mismo a\u00f1o, el cine gener\u00f3 189,3 millones de d\u00f3lares, mientras la televisi\u00f3n lleg\u00f3 a 506,2 millones*.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector audiovisual, compuesto por el cine, el video, la televisi\u00f3n abierta y la televisi\u00f3n por suscripci\u00f3n, es uno de los que m\u00e1s contribuye a las econom\u00edas iberoamericanas entre las Industrias Protegidas por el Derecho de Autor, IPDA, por sus elevados aportes al Producto Interno Bruto, PIB, sus altos niveles de facturaci\u00f3n y el volumen de sus exportaciones.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":""},"categories":[2464],"tags":[2507,2553],"areas":[],"countries":[],"programas":[],"coauthors":[],"_links":{"self":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts\/8841"}],"collection":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/comments?post=8841"}],"version-history":[{"count":0,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/posts\/8841\/revisions"}],"wp:attachment":[{"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/media?parent=8841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/categories?post=8841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/tags?post=8841"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/areas?post=8841"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/countries?post=8841"},{"taxonomy":"programas","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/programas?post=8841"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/cerlalc.org\/pt-br\/wp-json\/wp\/v2\/coauthors?post=8841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}